{"id":78760,"date":"2020-10-12T10:19:37","date_gmt":"2020-10-12T09:19:37","guid":{"rendered":"https:\/\/www.go-now.eu\/contact\/"},"modified":"2026-02-19T18:59:48","modified_gmt":"2026-02-19T17:59:48","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.go-now.eu\/fr\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"78760\" class=\"elementor elementor-78760 elementor-275\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8dbb45a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8dbb45a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-245dbea\" data-id=\"245dbea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9344222 elementor-widget elementor-widget-heading\" data-id=\"9344222\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">contact<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3359e93 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3359e93\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9fadf36\" data-id=\"9fadf36\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ba0e8c elementor-hidden-phone elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1ba0e8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.go-now.eu\/wp-content\/uploads\/2020\/10\/logo-go-now-white-stroke.svg\" class=\"attachment-large size-large wp-image-76823\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7cdebc elementor-widget elementor-widget-text-editor\" data-id=\"b7cdebc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Now Organic International BV<br \/>Zuid-Afrikaweg 14a<br \/>1432 DA Aalsmeer<br \/>NL 91 ABNA 0622 0626 38<br \/>TVA: NL852256000B01<br \/>Chambre de commerce: 56679130<br \/>NL-BIO-01: SKAL 027851<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ebbcb1e\" data-id=\"ebbcb1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8388f4 elementor-widget elementor-widget-heading\" data-id=\"a8388f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Envoyer un message<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0694da elementor-widget elementor-widget-text-editor\" data-id=\"e0694da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous avez une question concernant nos produits, l&rsquo;exp\u00e9dition ou les paiements ? Jetez alors un coup d&rsquo;\u0153il \u00e0 la page\u00a0<a href=\"https:\/\/www.go-now.eu\/fr\/questions-frequentes\/\"><span style=\"text-decoration: underline;\">questions fr\u00e9quemment pos\u00e9es<\/span><\/a>.\u00a0La plupart des r\u00e9ponses se trouvent d\u00e9j\u00e0 ici !<\/p><p class=\"p1\">Vous avez d&rsquo;autres questions ou commentaires ? Contactez nous gratuitement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-855c0a8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"855c0a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:info@go-now.eu\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Envoyer un e-mail<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/wa.me\/31644613433\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-messenger\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Direct direct par Whatsapp<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.go-now.eu\/fr\/questions-frequentes\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-question-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Voir les questions fr\u00e9quemment pos\u00e9es<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a097f0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5a097f0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5fdcfc\" data-id=\"a5fdcfc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f1a95f elementor-widget elementor-widget-google_maps\" data-id=\"8f1a95f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Zuid-Afrikaweg%2014a%2C%201432%20DA%20Aalsmeer&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Zuid-Afrikaweg 14a, 1432 DA Aalsmeer\"\n\t\t\t\t\taria-label=\"Zuid-Afrikaweg 14a, 1432 DA Aalsmeer\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>contact Now Organic International BVZuid-Afrikaweg 14a1432 DA AalsmeerNL 91 ABNA 0622 0626 38TVA: NL852256000B01Chambre de commerce: 56679130NL-BIO-01: SKAL 027851 Envoyer&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-78760","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact - Go Now<\/title>\n<meta name=\"description\" content=\"Vind hier al onze contactgegevens. Neem gerust contact met ons op voor vragen, opmerkingen of bestellingen. We helpen je graag verder zo snel\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.go-now.eu\/fr\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact - Go Now\" \/>\n<meta property=\"og:description\" content=\"Vind hier al onze contactgegevens. Neem gerust contact met ons op voor vragen, opmerkingen of bestellingen. We helpen je graag verder zo snel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.go-now.eu\/fr\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Go Now\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GoNowShots\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-19T17:59:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@gonowshots\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/contact\\\/\",\"url\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/contact\\\/\",\"name\":\"Contact - Go Now\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/contact\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/contact\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.go-now.eu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-go-now-white-stroke.svg\",\"datePublished\":\"2020-10-12T09:19:37+00:00\",\"dateModified\":\"2026-02-19T17:59:48+00:00\",\"description\":\"Vind hier al onze contactgegevens. Neem gerust contact met ons op voor vragen, opmerkingen of bestellingen. We helpen je graag verder zo snel\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/contact\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/contact\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.go-now.eu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-go-now-white-stroke.svg\",\"contentUrl\":\"https:\\\/\\\/www.go-now.eu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-go-now-white-stroke.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/\",\"name\":\"Go Now\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Go Now\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/#organization\",\"name\":\"Go Now\",\"alternateName\":\"Go Now\",\"url\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.go-now.eu\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-go-now-full-rgb@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.go-now.eu\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-go-now-full-rgb@2x.png\",\"width\":313,\"height\":313,\"caption\":\"Go Now\"},\"image\":{\"@id\":\"https:\\\/\\\/www.go-now.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GoNowShots\",\"https:\\\/\\\/x.com\\\/gonowshots\",\"https:\\\/\\\/www.instagram.com\\\/gonowshots\\\/\",\"https:\\\/\\\/pinterest.com\\\/gonowshots\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gonowshots\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact - Go Now","description":"Vind hier al onze contactgegevens. Neem gerust contact met ons op voor vragen, opmerkingen of bestellingen. We helpen je graag verder zo snel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.go-now.eu\/fr\/contact\/","og_locale":"fr_FR","og_type":"article","og_title":"Contact - Go Now","og_description":"Vind hier al onze contactgegevens. Neem gerust contact met ons op voor vragen, opmerkingen of bestellingen. We helpen je graag verder zo snel","og_url":"https:\/\/www.go-now.eu\/fr\/contact\/","og_site_name":"Go Now","article_publisher":"https:\/\/www.facebook.com\/GoNowShots","article_modified_time":"2026-02-19T17:59:48+00:00","twitter_card":"summary_large_image","twitter_site":"@gonowshots","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.go-now.eu\/fr\/contact\/","url":"https:\/\/www.go-now.eu\/fr\/contact\/","name":"Contact - Go Now","isPartOf":{"@id":"https:\/\/www.go-now.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.go-now.eu\/fr\/contact\/#primaryimage"},"image":{"@id":"https:\/\/www.go-now.eu\/fr\/contact\/#primaryimage"},"thumbnailUrl":"https:\/\/www.go-now.eu\/wp-content\/uploads\/2020\/10\/logo-go-now-white-stroke.svg","datePublished":"2020-10-12T09:19:37+00:00","dateModified":"2026-02-19T17:59:48+00:00","description":"Vind hier al onze contactgegevens. Neem gerust contact met ons op voor vragen, opmerkingen of bestellingen. We helpen je graag verder zo snel","breadcrumb":{"@id":"https:\/\/www.go-now.eu\/fr\/contact\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.go-now.eu\/fr\/contact\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.go-now.eu\/fr\/contact\/#primaryimage","url":"https:\/\/www.go-now.eu\/wp-content\/uploads\/2020\/10\/logo-go-now-white-stroke.svg","contentUrl":"https:\/\/www.go-now.eu\/wp-content\/uploads\/2020\/10\/logo-go-now-white-stroke.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.go-now.eu\/fr\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.go-now.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/www.go-now.eu\/fr\/#website","url":"https:\/\/www.go-now.eu\/fr\/","name":"Go Now","description":"","publisher":{"@id":"https:\/\/www.go-now.eu\/fr\/#organization"},"alternateName":"Go Now","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.go-now.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.go-now.eu\/fr\/#organization","name":"Go Now","alternateName":"Go Now","url":"https:\/\/www.go-now.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.go-now.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.go-now.eu\/wp-content\/uploads\/2023\/01\/logo-go-now-full-rgb@2x.png","contentUrl":"https:\/\/www.go-now.eu\/wp-content\/uploads\/2023\/01\/logo-go-now-full-rgb@2x.png","width":313,"height":313,"caption":"Go Now"},"image":{"@id":"https:\/\/www.go-now.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GoNowShots","https:\/\/x.com\/gonowshots","https:\/\/www.instagram.com\/gonowshots\/","https:\/\/pinterest.com\/gonowshots\/","https:\/\/www.linkedin.com\/company\/gonowshots\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.go-now.eu\/fr\/wp-json\/wp\/v2\/pages\/78760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.go-now.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.go-now.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.go-now.eu\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.go-now.eu\/fr\/wp-json\/wp\/v2\/comments?post=78760"}],"version-history":[{"count":5,"href":"https:\/\/www.go-now.eu\/fr\/wp-json\/wp\/v2\/pages\/78760\/revisions"}],"predecessor-version":[{"id":121534,"href":"https:\/\/www.go-now.eu\/fr\/wp-json\/wp\/v2\/pages\/78760\/revisions\/121534"}],"wp:attachment":[{"href":"https:\/\/www.go-now.eu\/fr\/wp-json\/wp\/v2\/media?parent=78760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}